{"id":7704,"date":"2024-03-22T08:25:12","date_gmt":"2024-03-22T07:25:12","guid":{"rendered":"https:\/\/www.ebilet.pl\/now\/?p=7704"},"modified":"2025-09-22T07:39:39","modified_gmt":"2025-09-22T06:39:39","slug":"nick-cave-o-wild-god-z-ta-plyta-nie-ma-zartow","status":"publish","type":"post","link":"https:\/\/www.ebilet.pl\/now\/nick-cave-o-wild-god-z-ta-plyta-nie-ma-zartow\/","title":{"rendered":"Nick Cave o &#8220;Wild God\u201d: Z t\u0105 p\u0142yt\u0105 nie ma \u017cart\u00f3w"},"content":{"rendered":"\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><p><span style=\"font-weight: 400;\">Prac\u0119 nad <strong>&#8220;Wild God\u201d <\/strong><\/span><a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/nick-cave-and-the-bad-seeds\"><strong>Nick Cave &amp; The Bad Seeds<\/strong><\/a><span style=\"font-weight: 400;\"> zacz\u0119li dok\u0142adnie 1 stycznia 2023 roku. Cave regularnie dzieli\u0142 si\u0119 w swoich mediach spo\u0142eczno\u015bciowych przemy\u015bleniami na temat procesu powstawania nowego albumu. O pocz\u0105tkowej blokadzie tw\u00f3rczej pisa\u0142:\u00a0<\/span><\/p>\n<p><strong>\u201cTo samo jest z ka\u017cd\u0105 p\u0142yt\u0105. Czuj\u0119 to znajome uczucie braku, jakbym by\u0142 wielk\u0105, g\u0142upi\u0105, pust\u0105 istot\u0105 w garniturze. Wszystko, co przypomina tw\u00f3rczy impuls, jest zakopane w jakiej\u015b omsza\u0142ej, \u017cabiej norze i \u015bpi, mam nadziej\u0119, \u017ce nie martwe. Musz\u0119 to przywo\u0142a\u0107, wybudzi\u0107 ze snu\u201d.<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">W maju i czerwcu sytuacja wygl\u0105da\u0142a ju\u017c bardziej obiecuj\u0105co. &#8220;Piosenki brzmi\u0105 \u015bwietnie\u201d \u2013 napisa\u0142 Nick. \u201c[Ale o tym, jak materia\u0142 b\u0119dzie wygl\u0105da finalnie] Nie dowiem si\u0119 tak naprawd\u0119, dop\u00f3ki nie wprowadz\u0119 Bad Seeds do studia i nie zrobimy albumu. Ale czuj\u0119 si\u0119 bardzo dobrze, bardzo pozytywnie\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Wk\u0142ad muzyk\u00f3w Bad Seeds zosta\u0142 dodany podczas sesji w Miraval w Prowansji i Soundtree w Londynie. W nagraniach dodatkowy udzia\u0142 wzi\u0119li <strong>Colin Greenwood (bas) i Luis Alma (gitara nylonowa, gitara akustyczna)<\/strong>.<\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"banner banner--layout-default section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"banner__wrapper\">\n                                        <div class=\"banner__bg\">\n                        <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554.jpg 1920w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-1024x576.jpg 1024w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-1536x864.jpg 1536w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-1280x720.jpg 1280w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-500x281.jpg 500w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-632x356.jpg 632w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-308x174.jpg 308w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>                    <\/div>\n                                                                                                    <div class=\"banner__text\">\n                        <div class=\"banner__title typo-h2 f-700\">Nick Cave and The Bad Seeds<\/div>\n                        <p class=\"banner__desc typo-14\"><\/p>\n                    <\/div>\n                                                            <div class=\"banner__link\">\n                        <a\n                            class=\"button button--theme-primary-yellow \"\n                            href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/nick-cave-and-the-bad-seeds\"\n                        >\n                            <p class=\"button__text typo-18\">Sprawd\u017a bilety<\/p>\n                                                    <\/a>\n                    <\/div>\n                                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><p><span style=\"font-weight: 400;\">Do tej pory muzyka Nick Cave &amp; The Bad Seeds najmocniej osadzona by\u0142a przede wszystkim w rocku i post-punku z wp\u0142ywami bluesa i folku. W wywiadzie dla &#8220;Rolling Stone&#8221; na pytanie, czy nowy album zaskoczy nas czym\u015b nowym i czy us\u0142yszymy np. znowu &#8211; jak to mia\u0142o miejsce w <strong>\u201cGhosteen\u201d<\/strong> &#8211; ambientowe brzmienia i analogow\u0105 elektronik\u0119 Cave odpowiedzia\u0142, \u017ce nie b\u0119dzie kontynuacji tego kierunku. Ale stwierdzi\u0142 te\u017c, \u017ce to te\u017c nie b\u0119dzie na pewno album stricte rockowy. <strong>\u201cNowa p\u0142yta ma mn\u00f3stwo energii, ale nie zosta\u0142a nagrana jako rock&#8217;n&#8217;rollowa\u201d \u2013 powiedzia\u0142. \u201cPo prostu szukamy r\u00f3\u017cnych sposob\u00f3w dotarcia do emocjonalnego sedna tego, o czym pr\u00f3buj\u0119 pisa\u0107\u201d.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cave zapowiedzia\u0142, \u017ce &#8220;Wild God\u201d ma by\u0107 \u201cpe\u0142en tajemnic\u201d ale, \u017ce te\u017c istniej\u0105 na nim momenty, kt\u00f3re z sentymentem dotykaj\u0105 przesz\u0142o\u015bci Bad Seeds.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ostatnia wiadomo\u015b\u0107 Cave\u2019a dotycz\u0105ca jego nowego albumu pojawi\u0142a si\u0119 w listopadzie 2023 roku. Og\u0142osi\u0142 wtedy na swojej stronie, \u017ce miksuje ju\u017c nowe piosenki:<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u201cGdy zalewaj\u0105 mnie te wszystkie nowe i pi\u0119kne piosenki, to czuj\u0119 si\u0119 zainspirowany, aby powiedzie\u0107 wam, \u017ce przywilej wykonywania tego najwra\u017cliwszego z zawod\u00f3w \u2013 bycia piosenkarzem \u2013 jest przeogromny\u201d<\/strong> \u2013 napisa\u0142.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Kr\u0105\u017cek zosta\u0142 wyprodukowany przez Cave&#8217;a i Warrena Ellisa oraz zmiksowany przez Davida Fridmanna. <\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Ghosteen\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/album\/5TkXgoeyGznBNOjrw17eA7?si=hYB1LxNRTWa1SL2VR1z3UA&#038;nd=1&#038;dlsi=8a3a49b34cd540b2&#038;utm_source=oembed\"><\/iframe> \n<\/div><\/figure>\n\n\n<section class=\"gap-block  section-margin-32 section-margin-32\"><\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><h2><b>&#8220;Wild God\u201d wyskakuje z g\u0142o\u015bnika i poch\u0142ania bez reszty<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Gdy promocja nowego album ruszy\u0142a ju\u017c na dobre Nick promowa\u0142 wydawnictwo:\u00a0<\/span><\/p>\n<p><strong>&#8220;Mam nadziej\u0119, \u017ce album wywrze na s\u0142uchaczach taki sam wp\u0142yw, jaki wywar\u0142 na mnie. Ta p\u0142yta wybucha z g\u0142o\u015bnika, a ja daj\u0119 si\u0119 jej porwa\u0107. To skomplikowany album, ale jest te\u017c g\u0142\u0119boki i rado\u015bnie zara\u017aliwy. Nagrywaj\u0105c p\u0142yt\u0119 nigdy nie mamy jakiego\u015b wielkiego planu. Albumy odzwierciedlaj\u0105 raczej stan emocjonalny autor\u00f3w i muzyk\u00f3w, kt\u00f3rzy je zagrali. S\u0142uchaj\u0105c nowych piosenek wydaje si\u0119, \u017ce jeste\u015bmy szcz\u0119\u015bliwi\u201d.<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">To na pewno jest ogromna wolta po ostatnim &#8211; doskona\u0142ym! &#8211; albumie \u201cGhostteen\u201d z 2019 roku, o kt\u00f3rym &#8220;NME&#8221; napisa\u0142o, \u017ce \u201cto jeden z najbardziej pora\u017caj\u0105co dok\u0142adnych opis\u00f3w \u017ca\u0142oby, jakie kiedykolwiek us\u0142yszysz. Jednak, co zaskakuj\u0105ce, jest to r\u00f3wnie\u017c jedno z najbardziej pocieszaj\u0105cych dzie\u0142. Niewielu medytacjom nad \u017ca\u0142ob\u0105 udaje si\u0119 tak dobrze pokona\u0107 rozpacz i osi\u0105gn\u0105\u0107 katharsis\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Z wypowiedzi Cave&#8217;a wynika, \u017ce &#8220;Wild God\u201d mo\u017ce stanowi\u0107 domkni\u0119cie tego procesu i Nick Cave &amp; The Bad Seeds wchodz\u0105 w nowy etap, w kt\u00f3rym pomimo straty, b\u00f3lu i przeciwno\u015bci bywa obecna te\u017c rado\u015b\u0107.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>\u201cZ t\u0105 p\u0142yt\u0105 nie ma \u017cart\u00f3w, mocno uderza. Podnosi na duchu. Porusza ci\u0119. Uwielbiam j\u0105\u201d<\/strong> &#8211; zapowiada Nick Cave.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Utw\u00f3r &#8220;Wild God\u201d to pierwszy przedsmak albumu, kt\u00f3ry ju\u017c sami mogli\u015bmy ods\u0142ucha\u0107 i oceni\u0107.<\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<figure class=\"wp-block-embed is-provider-youtube wp-block-embed-youtube\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Nick Cave &amp; The Bad Seeds - Wild God (Official Audio)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/uAgsn7la3jg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> \n<\/div><\/figure>\n\n\n<section class=\"gap-block  section-margin-32 section-margin-32\"><\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><p><span style=\"font-weight: 400;\">Zesp\u00f3\u0142 zapowiada, \u017ce na nowym albumie <strong>\u201cma ta\u0144czy\u0107 mi\u0119dzy konwencj\u0105 a eksperymentem\u201d<\/strong>. Czy promuj\u0105cy p\u0142yt\u0119 utw\u00f3r spe\u0142nia te obietnice? Na pewno mamy tutaj uk\u0142on w stron\u0119 \u201cstarego\u201d, bo kawa\u0142ek utrzymany jest mocno w duchu The Bad Seeds z lat 90. \u201cWild God\u201d z pewno\u015bci\u0105 wype\u0142nia te\u017c niesamowita lekko\u015b\u0107 oraz ten entuzjazm, optymizm i energia, o kt\u00f3rej tyle m\u00f3wi Cave! Faktycznie te emocje si\u0119 tutaj rozlewaj\u0105 i triumfuj\u0105. A eksperyment? W czwartej minucie utworu ocieramy si\u0119 lekko o gospel, gdy melodeklamacja Cave&#8217;a wzbogacona zostaje o ch\u00f3rki. Jednak ten zabieg nie jest niczym specjalnie nowatorskim i przypomina <strong>\u201cAbattoir Blues\u201d<\/strong>. Mo\u017ce kolejne utwory przynios\u0105 wi\u0119cej zaskocze\u0144? Czekamy wi\u0119c na wi\u0119cej.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">To, co jeszcze zdradzi\u0142 Cave, to to, \u017ce b\u0119dziemy mie\u0107 do czynienia z albumem koncepcyjnym, na kt\u00f3ry sk\u0142ada si\u0119 11 utwor\u00f3w, kt\u00f3re pod wzgl\u0119dem literackim i muzycznym stworz\u0105 ca\u0142o\u015b\u0107.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Opiniami o albumie zd\u0105\u017cy\u0142 si\u0119 z mediami podzieli\u0107 ju\u017c Kenny Gates &#8211; wsp\u00f3\u0142za\u0142o\u017cyciel i dyrektor generalny wytw\u00f3rni <strong>PIAS<\/strong>, w kt\u00f3rej zesp\u00f3\u0142 wyda\u0142 p\u0142yt\u0119:<\/span><\/p>\n<p><strong>\u201cNowy album jest niesamowity. Moim zdaniem jest to jego najlepszy album w historii The Bad Seeds i zas\u0142uguje na \u015bwiatowy sukces\u201d.<\/strong><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"tickets-slider  section-margin-32\"\n    data-tickets-slider\n    data-item-list-name=\"Karuzela z buttonami\"\n    data-item-list-id=\"karuzela_z_buttonami\"\n    >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"tickets-slider__main\">\n                    <div class=\"tickets-slider__nav tickets-slider__nav--prev\">\n                        <div class=\"button button--withIcon button--theme-white-blur button--size-fixed-48\" data-tickets-slider-prev>\n                            <span class=\"button__icon icon icon-chevron-left\"><\/span>\n                        <\/div>\n                    <\/div>\n                    <div class=\"tickets-slider__nav tickets-slider__nav--next\">\n                        <div class=\"button button--withIcon button--theme-white-blur button--size-fixed-48\" data-tickets-slider-next>\n                            <span class=\"button__icon icon icon-chevron-right\"><\/span>\n                        <\/div>\n                    <\/div>\n                    <div class=\"tickets-slider__slider swiper\" data-tickets-slider-slider>\n                        <div class=\"tickets-slider__sliderWrapper swiper-wrapper\">\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"103616\"\n                                    data-name=\"Another Pink Floyd\"\n                                    data-brand=\"FANTOM MEDIA Micha\u0142 Kapu\u015bciarz\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Bia\u0142ystok, Gorz\u00f3w Wielkopolski, Krak\u00f3w i inne\"\n                                    data-venue=\"Arena Ostr\u00f3w\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/another-pink-floyd-marek-raduli\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/vv5cv4hb\/another-pink-floyd-pion-736.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/another-pink-floyd-marek-raduli\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"29466\"\n                                    data-name=\"Queen Symfonicznie \u2013 trasa XV-lecia\"\n                                    data-brand=\"Piosenka Plus\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Bia\u0142ystok, Bielsko-Bia\u0142a, Gda\u0144sk i inne\"\n                                    data-venue=\"Filharmonia Zielonog\u00f3rska im. Tadeusza Bairda\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/queen-symfonicznie\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/by0fduy3\/queensymfoniczniexvlecie-1.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/queen-symfonicznie\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"68779\"\n                                    data-name=\"Zadzwo\u0144cie po milicj\u0119\"\n                                    data-brand=\"VISUAL PRODUCTION Sp. z o.o. \"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Gorz\u00f3w Wielkopolski, Katowice, \u0141\u00f3d\u017a i inne\"\n                                    data-venue=\"Hala Spodek\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/zadzwoncie-po-milicje\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/z5pgmlm0\/ebilet-552x736px-7b19a255-52f8-414a-ba5c-940dd8da8a6c.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/zadzwoncie-po-milicje\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"94046\"\n                                    data-name=\"BLIND CHANNEL\"\n                                    data-brand=\"Winiary Bookings sp. z o. o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Krak\u00f3w, Warszawa\"\n                                    data-venue=\"Klub Proxima\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/blind-channel\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/heakcnq4\/blind-channel-ebilet-strona-wydarzenia-pion-wspo-lne.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/blind-channel\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"94910\"\n                                    data-name=\"Muzyka Zespo\u0142u Nirvana Symfonicznie\"\n                                    data-brand=\"Piosenka Plus\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Gorz\u00f3w Wielkopolski, \u0141a\u0144cut, Nysa i inne\"\n                                    data-venue=\"Miejskie Centrum Kultury, Gorz\u00f3w Wielkopolski\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/nirvana-symfonicznie\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/paofi20m\/552x763-63f08d4d-3f99-0184-5010-e673682fe97f.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/nirvana-symfonicznie\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"10619\"\n                                    data-name=\"\u015awietliki\"\n                                    data-brand=\"Fundacja Student\u00f3w i Absolwent\u00f3w AGH w Krakowie\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Krak\u00f3w\"\n                                    data-venue=\"Klub Studio\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/swietliki\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/bb1bacv5\/st-swietliki-05-12_ebilet-552x736-1.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/swietliki\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"6263\"\n                                    data-name=\"IRA\"\n                                    data-brand=\"Agencja Artystyczna Brussa Jaros\u0142aw Brussa Iwona Brussa Zuzanna \"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Toru\u0144, Tychy, Wroc\u0142aw\"\n                                    data-venue=\"Teatr Ma\u0142y  w Tychach\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/ira\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/s35cup1a\/552x736-2-1-bcc906fe-3e20-4a00-8fad-3bc2b5052fe4.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/ira\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"121218\"\n                                    data-name=\"Diary Of Dreams\"\n                                    data-brand=\"Progresja\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Warszawa\"\n                                    data-venue=\"Progresja\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/diary-of-dreams\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/xs2l1roa\/pion-dod-1c2e216b-9c55-4209-af9d-317afb962913.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/diary-of-dreams\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"5751\"\n                                    data-name=\"Freddie Mercury Rock-Operowo przy \u015bwiecach\"\n                                    data-brand=\"Copernicus Sp\u00f3\u0142ka z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Bielsko-Bia\u0142a, Bydgoszcz, Krak\u00f3w i inne\"\n                                    data-venue=\"Sala Redutowa - Kamienica &quot;Pod Or\u0142em&quot;\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/freddie-mercury-rock-operowo\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/xrhpj4s5\/freddie-mercury-opera-show-552x736-px-e2f617db-f1c6-4e8d-a457-635fc1b031af.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/freddie-mercury-rock-operowo\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"151582\"\n                                    data-name=\"Zvezda po imeni Solnce - KINO Symphony Tribute\"\n                                    data-brand=\"Luckystar,s.r.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Gda\u0144sk, Warszawa\"\n                                    data-venue=\"Teatr Palladium w Warszawie\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/kino\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ff1my13k\/tsoy-552_736-300de170-4d6e-4339-888e-b2369357bd21.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/kino\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"148914\"\n                                    data-name=\"Baby Lasagna\"\n                                    data-brand=\"Winiary Bookings sp. z o. o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Krak\u00f3w, Pozna\u0144, Warszawa\"\n                                    data-venue=\"Klub Tama\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/baby-lasagna\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/s0fjvlmt\/baby-lasagna-ebilet-strona-wydarzenia-pion-wsp_lne-bcc5aef0-8eb2-47c6-b22d-5d746c61b5ca.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/baby-lasagna\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"169635\"\n                                    data-name=\"Manchester trasa 20 lat\"\n                                    data-brand=\"Lizard King\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Gda\u0144sk, Rybnik, Toru\u0144 i inne\"\n                                    data-venue=\"Odessa Club\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/manchester\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/qsrp1mid\/trasa-552x736-bez-miast-27e20225-6568-41d5-a815-22ac82c64b5c.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/manchester\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"174489\"\n                                    data-name=\"Rock przy \u015bwiecach\"\n                                    data-brand=\"Royal Tributes Sp. z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Bia\u0142ystok, Kielce, Krak\u00f3w i inne\"\n                                    data-venue=\"Nowohuckie Centrum Kultury w Krakowie\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/rock-przy-swiecach\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/jtxjvwxg\/552x736-1bede421-ef80-4b28-8022-46d9748e5b60.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/rock-przy-swiecach\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"178032\"\n                                    data-name=\"Muzyka Queen i Eltona Johna na 28. pi\u0119trze\"\n                                    data-brand=\"SVITLO CONCERT Sp. z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Warszawa\"\n                                    data-venue=\"Sky Hall by Svitlo Concert\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/muzyka-queen-i-eltona-johna\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/xk2fokit\/552_736-queen-i-elton-john-45ba92a6-63e6-4fcc-a7dd-a8d110220060.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/muzyka-queen-i-eltona-johna\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"178059\"\n                                    data-name=\"Klasyka Rocka na 28. pi\u0119trze\"\n                                    data-brand=\"SVITLO CONCERT Sp. z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Warszawa\"\n                                    data-venue=\"Sky Hall by Svitlo Concert\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/klasyka-rocka-na-28-pietrze\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/bomlu01s\/552_736-klasyka-rocka-1-524982de-4c74-453d-9759-d38cea5c4ffe.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/klasyka-rocka-na-28-pietrze\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"181566\"\n                                    data-name=\"Queen Classic Concert By Candle Glow\"\n                                    data-brand=\"Copernicus Sp\u00f3\u0142ka z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Krak\u00f3w, Warszawa\"\n                                    data-venue=\"Klasztor O.O. Bernardyn\u00f3w\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/royal-chopin-hall\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/kyndi0f0\/queen-classic-krak_w-552x736-px-by-candle-glow-7c7a331d-b9d9-432e-b4ab-2b0a679f4a61.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/royal-chopin-hall\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"182461\"\n                                    data-name=\"&quot;M\u00f3wi\u0105 o mnie w mie\u015bcie...&quot; - Urodziny Ry\u015bka Riedla\"\n                                    data-brand=\"SWIK Nasze Miasto Wroc\u0142aw\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Wroc\u0142aw\"\n                                    data-venue=\"Stary Klasztor\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/urodziny-ryska-riedla\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/j0klrcnc\/600x850-16-1-dbc22d07-f6af-4895-bec5-188342de3666.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/urodziny-ryska-riedla\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"64455\"\n                                    data-name=\"Budka Suflera\"\n                                    data-brand=\"AGENCJA ARTYSTYCZNA BRUSSA ZUZANNA BRUSSA\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"\u0141\u00f3d\u017a, Pozna\u0144, Szczecin\"\n                                    data-venue=\"Aula Uniwersytetu im. Adama Mickiewicza\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/budka-suflera\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/nodjpqhc\/552x736-440b2d4b-96e6-4745-b1df-734d2a4584e2.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/budka-suflera\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"66419\"\n                                    data-name=\"Clan of Xymox\"\n                                    data-brand=\"SWIK Nasze Miasto Wroc\u0142aw\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Wroc\u0142aw\"\n                                    data-venue=\"Stary Klasztor\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/clan-of-xymox\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/mh5bsm2p\/clan-of-xymox-600-x-850-px-1-76107dc8-3d1a-40a9-abb7-ccac953c5388.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/clan-of-xymox\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"183034\"\n                                    data-name=\"Koncert przy \u015bwiecach \u2013 Rockowe ballady\"\n                                    data-brand=\"Fundacja na Rzecz Pomocy Pestka\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Wroc\u0142aw\"\n                                    data-venue=\"Aula NOT\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/rockowe-ballady\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ct4htuvt\/2_rockowe-ballady-552-x-736-px-fd77277d-4666-40e0-ac40-98e075eed508.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/rockowe-ballady\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><h2>Nick<b> Cave &amp; The Bad Seeds og\u0142aszaj\u0105 tras\u0119 koncertow\u0105 \u201cWild God\u201d<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Nick Cave zapewnia, \u017ce nowy album jest wprost stworzony do grania na \u017cywo:<\/span><\/p>\n<p><strong>\u201cNigdy nie my\u015bl\u0119 jak dany album zabrzmi na \u017cywo. Proces powstawania tekst\u00f3w jest zbyt skomplikowany, aby zastanawia\u0107 si\u0119 nad t\u0105 kwesti\u0105. Ale kiedy s\u0142ucham &#8220;Wild God&#8221;, mam poczucie, \u017ce z tymi piosenkami mo\u017cemy na \u017cywo zrobi\u0107 co\u015b epickiego. Jeste\u015bmy tym bardzo podekscytowani. Ten album sprawia wra\u017cenie, jakby by\u0142 stworzony dla sceny \u2014 m\u00f3wi.<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">W ramach <strong>The Wild God Tour<\/strong> zesp\u00f3\u0142 wyst\u0105pi w Polsce na dw\u00f3ch koncertach: <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/nick-cave-and-the-bad-seeds\"><strong>10.10.2024 w Atlas Arenie w \u0141odzi oraz 11.10.2024 w TAURON Arenie Krak\u00f3w<\/strong>.<\/a><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Go\u015bciem specjalnym koncert\u00f3w w naszym kraju b\u0119dzie <\/span><span style=\"font-weight: 400;\">brytyjski, post-punkowy zesp\u00f3\u0142 <\/span><span style=\"font-weight: 400;\">zesp\u00f3\u0142 <\/span><strong><a href=\"https:\/\/www.ebilet.pl\/artysta\/dry-cleaning\">Dry Cleaning<\/a><\/strong><span style=\"font-weight: 400;\">.<\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<figure class=\"wp-block-embed is-provider-youtube wp-block-embed-youtube\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: New Long Leg\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/album\/4oNy189uvEgnJKNLsWx9Zz?utm_source=oembed\"><\/iframe> \n<\/div><\/figure>\n\n\n<section class=\"gap-block  section-margin-32 section-margin-32\"><\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><h2><b>Kap\u0142an gotyckiego rocka \u015bpiewa \u00c9dith Piaf<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Nick Cave od ponad 40 lat jest niezwykle p\u0142odnym artyst\u0105 &#8211;\u00a0 solo i ze swoimi zespo\u0142ami wyda\u0142 \u0142\u0105cznie ponad 20 album\u00f3w studyjnych, 11 album\u00f3w ze \u015bcie\u017ck\u0105 d\u017awi\u0119kow\u0105 i wiele album\u00f3w koncertowych. Pisze te\u017c powie\u015bci i poezj\u0119.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">W niedawnym wywiadzie dla BBC Cave stwierdzi\u0142, \u017ce w wieku 65 lat czasami my\u015bli o porzuceniu muzyki:<\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"quote-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"quote-block__wrapper\">\n                    <p class=\"quote-block__quote typo-32\">\u201cNie mam nic przeciwko przej\u015bciu na emerytur\u0119. Cz\u0119sto rozmawiam o tym z moj\u0105 \u017con\u0105 Susie. Czasami moja praca jest niezwykle intensywna i pragnienie wycofania si\u0119 z widoku publicznego jest czasami ogromne. Mam jednak poczucie obowi\u0105zku wobec mojej publiczno\u015bci i mojego rzemios\u0142a. Dlatego musz\u0119 to kontynuowa\u0107 tak d\u0142ugo, jak d\u0142ugo czuj\u0119, \u017ce robi\u0119 co\u015b warto\u015bciowego\u201d<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><p><span style=\"font-weight: 400;\">Trasa i nowy album to nie wszystkie niespodzianki, jakie na ten rok przygotowa\u0142 dla nas Nick. Artysta nie zwalnia tempa i wci\u0105\u017c zaskakuje nowymi projektami. Trwaj\u0105 obecnie prace nad telewizyjn\u0105 adaptacj\u0105 jego powie\u015bci <strong>\u201c\u015amier\u0107 Bunny&#8217;ego Munro\u201d<\/strong>, w kt\u00f3rej zagra znany z <strong>\u201cDoktora Who\u201d<\/strong>, <strong>Matt Smith<\/strong>. Cave by\u0142 te\u017c wsp\u00f3\u0142tw\u00f3rc\u0105 muzyki do filmu biograficznego o Amy Winehouse oraz \u015bcie\u017cki d\u017awi\u0119kowej do dramatu historycznego <strong>Jacka Antonoffa \u201cThe New Look\u201d<\/strong>, gdzie wykona\u0142 przepi\u0119kny, wzruszaj\u0105cy cover utworu <strong>\u201cLa Vie En Rose\u201d \u00c9dith Piaf<\/strong>.<\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La Vie En Rose (The New Look: Season 1 (Apple TV+ Original Series Soundtrack))\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/CtAU6mEKxWo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<section class=\"gap-block  section-margin-32 section-margin-32\"><\/section>\n\n\n<section class=\"events-slider-block  section-margin-32\" data-events-slider-block data-carousel-title=\"Gor\u0105ce wydarzenia\" data-carousel-type=\"karuzela_z_t\u0142em\" data-item-list-name=\"Karuzela z t\u0142em Gor\u0105ce wydarzenia\" data-item-list-id=\"karuzela_z_t\u0142em Gor\u0105ce wydarzenia\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"events-slider-block__wrapper\">\n                                            <div class=\"events-slider-block__bg\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554.jpg 1920w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-1024x576.jpg 1024w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-1536x864.jpg 1536w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-1280x720.jpg 1280w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-500x281.jpg 500w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-632x356.jpg 632w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-308x174.jpg 308w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div>\n                                                                <div class=\"events-slider-block__top\">\n                                                            <div class=\"events-slider-block__title desktop\">\n                                    <h2 class=\"typo-h2\">Gor\u0105ce wydarzenia<\/h2>\n                                <\/div>\n                                                                                        <div class=\"events-slider-block__title mobile\">\n                                    <h2 class=\"typo-h2\">Gor\u0105ce wydarzenia<\/h2>\n                                <\/div>\n                                                    <\/div>\n                                                            <div class=\"events-slider-block__main\">\n                        <div class=\"events-slider-block__nav events-slider-block__nav--prev\">\n                            <div class=\"button button--withIcon button--theme-white-blur button--size-fixed-48\" data-events-prev>\n                                <span class=\"button__icon icon icon-chevron-left\"><\/span>\n                            <\/div>\n                        <\/div>\n                        <div class=\"events-slider-block__nav events-slider-block__nav--next\">\n                            <div class=\"button button--withIcon button--theme-white-blur button--size-fixed-48\" data-events-next>\n                                <span class=\"button__icon icon icon-chevron-right\"><\/span>\n                            <\/div>\n                        <\/div>\n                        <div class=\"events-slider-block__slider\">\n                            <div class=\"swiper\" data-events-slider>\n                                <div class=\"events-slider-block__sliderWrapper swiper-wrapper\">\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/fontaines-dc\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ovge4bna\/fontaines_dc_portal_552x736.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Fontaines D.C. EU TOUR 2026<\/p>\n            <\/div>\n            <div class=\"card-event__date\">31.10.2026-31.10.2026<\/div>\n            <div class=\"card-event__location\">\u0141\u00f3d\u017a<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/tokio-hotel\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/i02j3uly\/tokio-hotel-552.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Tokio Hotel<\/p>\n            <\/div>\n            <div class=\"card-event__date\">19.08.2027-19.08.2027<\/div>\n            <div class=\"card-event__location\">Warszawa<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/opener-festival\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/qkso1del\/opene_2027_tameimpala_552x736_ebilet-1d7aa61e-0a2a-4f3b-b538-d84518354aa2.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Open&#8217;er Festival 2027<\/p>\n            <\/div>\n            <div class=\"card-event__date\">30.06.2027-30.06.2027<\/div>\n            <div class=\"card-event__location\">Gdynia<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/sport\/sporty-walki\/ksw-gala\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/cz4hwoy5\/ksw122_552x736-kopia-2bfd4e82-ebbc-475a-901b-7cd82d226339.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>XTB KSW 122<\/p>\n            <\/div>\n            <div class=\"card-event__date\">10.10.2026-10.10.2026<\/div>\n            <div class=\"card-event__location\">Rzesz\u00f3w<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/sport\/lekkoatletyka\/memorial-kamili-skolimowskiej\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ebddns15\/552x736-78da7a2f-a7cf-4711-af9b-beba90926c7e.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Silesia Memoria\u0142 Kamili Skolimowskiej<\/p>\n            <\/div>\n            <div class=\"card-event__date\">15.08.2027-15.08.2027<\/div>\n            <div class=\"card-event__location\">Chorz\u00f3w<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/piosenka\/koncert-koled-i-pastoralek-golec-uorkiestra\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/sqlacf5s\/golec_552x736_ebilet-c90c1dab-7443-46cc-b6f7-252554a5cab4.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Golec uOrkiestra &#8211; Koncert Kol\u0119d i Pastora\u0142ek<\/p>\n            <\/div>\n            <div class=\"card-event__date\">18.12.2026-18.12.2026<\/div>\n            <div class=\"card-event__location\">Bielsko-Bia\u0142a, Bydgoszcz, Gda\u0144sk i inne<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/hip-hop-rap\/gombao33\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ctcikvkb\/gombao_bez_napisu-2ebe28b7-760a-4987-8d6c-0cb2fe6f2203.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>G33 Tour &#8211; Tadeo x Szczepan x Wygu\u015b x Mata<\/p>\n            <\/div>\n            <div class=\"card-event__date\">12.09.2026-12.09.2026<\/div>\n            <div class=\"card-event__location\">Bydgoszcz, Gwi\u017adziny, Kra\u015bnik i inne<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/sport\/sporty-druzynowe\/koszykowka-mecz\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/hoxono4g\/podstawowe_portal-98225706-f40f-4253-9b63-9f6c375fb13f.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Kwalifikacje do Mistrzostw \u015awiata w koszyk\u00f3wce m\u0119\u017cczyzn 2027: Polska \u2013 Chorwacja<\/p>\n            <\/div>\n            <div class=\"card-event__date\">27.11.2026-27.11.2026<\/div>\n            <div class=\"card-event__location\">Gliwice<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/pitbull\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/5lzfwzwf\/pitbull_552x736-51986cca-48f5-4419-a9c5-cba531ed65a3.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Pitbull &#8211; I&#8217;m Back!<\/p>\n            <\/div>\n            <div class=\"card-event__date\">27.11.2026-27.11.2026<\/div>\n            <div class=\"card-event__location\">Gda\u0144sk\/Sopot, \u0141\u00f3d\u017a<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/russell-crowe\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/dajolyng\/rusel_pion-738c048c-2504-4de3-a226-d83518cf8463.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Russell Crowe\u2019s Indoor Garden Party<\/p>\n            <\/div>\n            <div class=\"card-event__date\">05.06.2027-05.06.2027<\/div>\n            <div class=\"card-event__location\">\u0106miel\u00f3w<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/hip-hop-rap\/otsochodzi\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ucuizr2w\/tt-552-x-736-kopia.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Otsochodzi &#8211; RIOTT<\/p>\n            <\/div>\n            <div class=\"card-event__date\">01.10.2026-01.10.2026<\/div>\n            <div class=\"card-event__location\">Gda\u0144sk, Krak\u00f3w, Pozna\u0144 i inne<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/biznes\/wystawa\/van-gogh\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/rx0pgtm4\/nowa-ebilet-_vg-__-lublin_-552-736-5ddf74a4-5cec-41cd-9f00-a4baa0f7a221.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>VAN GOGH \u2013 Wystawa Immersyjna &#8211; Lublin<\/p>\n            <\/div>\n            <div class=\"card-event__date\">15.09.2026-15.09.2026<\/div>\n            <div class=\"card-event__location\">Lublin<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/up-to-date-festival\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/jfdlnoqn\/ebilet-552x736-portal-wersja-2-c38ddeaf-bf05-4f54-9e4d-377e6b572335.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Up To Date Festival 2027<\/p>\n            <\/div>\n            <div class=\"card-event__date\">27.05.2027-27.05.2027<\/div>\n            <div class=\"card-event__location\">Bia\u0142ystok<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/take-that\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/eiqdozli\/ebilet-552x736-take-that.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Take That<\/p>\n            <\/div>\n            <div class=\"card-event__date\">13.06.2027-13.06.2027<\/div>\n            <div class=\"card-event__location\">Warszawa<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/olsztyn-green-festival\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ivzhtv3z\/1080x1350_ogf_edycja_2027-18faf89b-3a6e-4aa9-b07b-593f24448a27.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Olsztyn Green Festival 2027<\/p>\n            <\/div>\n            <div class=\"card-event__date\">13.08.2027-13.08.2027<\/div>\n            <div class=\"card-event__location\">Olsztyn<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"events-slider-block__events swiper\" data-events-events-descriptions>\n                            <div class=\"events-slider-block__eventsWrapper swiper-wrapper\">\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/fontaines-dc\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Fontaines D.C. EU TOUR 2026<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        31.10.2026-31.10.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">\u0141\u00f3d\u017a<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/tokio-hotel\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Tokio Hotel<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        19.08.2027-19.08.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Warszawa<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/opener-festival\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Open&#039;er Festival 2027<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        30.06.2027-03.07.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Gdynia<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/sport\/sporty-walki\/ksw-gala\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>XTB KSW 122<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        10.10.2026-10.10.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Rzesz\u00f3w<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/sport\/lekkoatletyka\/memorial-kamili-skolimowskiej\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Silesia Memoria\u0142 Kamili Skolimowskiej<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        15.08.2027-15.08.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Chorz\u00f3w<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/piosenka\/koncert-koled-i-pastoralek-golec-uorkiestra\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Golec uOrkiestra &#8211; Koncert Kol\u0119d i Pastora\u0142ek<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        18.12.2026-17.01.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Bielsko-Bia\u0142a, Bydgoszcz, Gda\u0144sk i inne<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/hip-hop-rap\/gombao33\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>G33 Tour &#8211; Tadeo x Szczepan x Wygu\u015b x Mata<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        12.09.2026-04.10.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Bydgoszcz, Gwi\u017adziny, Kra\u015bnik i inne<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/sport\/sporty-druzynowe\/koszykowka-mecz\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Kwalifikacje do Mistrzostw \u015awiata w koszyk\u00f3wce m\u0119\u017cczyzn 2027: Polska \u2013 Chorwacja<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        27.11.2026-27.11.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Gliwice<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/pitbull\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Pitbull &#8211; I&#039;m Back!<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        27.11.2026-03.12.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Gda\u0144sk\/Sopot, \u0141\u00f3d\u017a<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/russell-crowe\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Russell Crowe\u2019s Indoor Garden Party<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        05.06.2027-05.06.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">\u0106miel\u00f3w<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/hip-hop-rap\/otsochodzi\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Otsochodzi &#8211; RIOTT<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        01.10.2026-03.12.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Gda\u0144sk, Krak\u00f3w, Pozna\u0144 i inne<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/biznes\/wystawa\/van-gogh\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>VAN GOGH \u2013 Wystawa Immersyjna &#8211; Lublin<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        15.09.2026-31.12.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Lublin<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/up-to-date-festival\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Up To Date Festival 2027<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        27.05.2027-28.05.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Bia\u0142ystok<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/take-that\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Take That<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        13.06.2027-13.06.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Warszawa<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/olsztyn-green-festival\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Olsztyn Green Festival 2027<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        13.08.2027-13.08.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Olsztyn<\/div>\n                                <\/div>\n                                                        <\/div>\n                        <\/div>\n                        <div class=\"events-slider-block__pagination\">\n                            <div class=\"swiper-pagination slider-pagination slider-pagination--theme-white\" data-events-slider-pagination><\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"events-slider-block__bottom\">\n                                                                                <div class=\"events-slider-block__link desktop\">\n                                    <a\n                                        class=\"button button--size-small button--theme-primary-yellow button--withIconLeft\"\n                                        href=\"https:\/\/www.ebilet.pl\/\">\n                                                                                    <div class=\"button__icon\"><img loading=\"lazy\" decoding=\"async\" width=\"30\" height=\"30\" src=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/01\/ticket-cinema-entertainment-coupon-discount-sale_30px.png\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\n                                                                                <p class=\"button__text typo-18\">Kup na eBilet.pl<\/p>\n                                    <\/a>\n                                <\/div>\n                                                                                <div class=\"events-slider-block__link mobile\">\n                                    <a\n                                        class=\"button button--size-small button--theme-primary-yellow button--withIconLeft\"\n                                        href=\"https:\/\/www.ebilet.pl\/\">\n                                                                                    <div class=\"button__icon\"><img loading=\"lazy\" decoding=\"async\" width=\"30\" height=\"30\" src=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/01\/ticket-cinema-entertainment-coupon-discount-sale_30px.png\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\n                                                                                <p class=\"button__text typo-18\">Kup na eBilet.pl<\/p>\n                                    <\/a>\n                                <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Nick Cave &#038; The Bad Seeds og\u0142osili, \u017ce ruszaj\u0105 w tras\u0119 i jesieni\u0105 zagraj\u0105 dwa koncerty w Polsce. To nast\u0119pstwo wydania 18 studyjnego albumu zespo\u0142u, kt\u00f3ry uka\u017ce si\u0119 30 sierpnia. Co wiemy o nowym wydawnictwie?<\/p>\n","protected":false},"author":8,"featured_media":8456,"comment_status":"open","ping_status":"open","sticky":false,"template":"page-templates\/article-premium.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"article_tag":[26,31,215,82,71,43],"article_type":[554],"class_list":["post-7704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","article_tag-koncerty","article_tag-muzyka","article_tag-nick-cave","article_tag-plyty","article_tag-polecane","article_tag-rock","article_type-muzyka"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/posts\/7704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/comments?post=7704"}],"version-history":[{"count":3,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/posts\/7704\/revisions"}],"predecessor-version":[{"id":9862,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/posts\/7704\/revisions\/9862"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/media\/8456"}],"wp:attachment":[{"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/media?parent=7704"}],"wp:term":[{"taxonomy":"article_tag","embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/article_tag?post=7704"},{"taxonomy":"article_type","embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/article_type?post=7704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}