{"id":26619,"date":"2024-07-08T10:13:56","date_gmt":"2024-07-08T09:13:56","guid":{"rendered":"https:\/\/www.ebilet.pl\/now\/?p=26619"},"modified":"2025-09-19T19:49:02","modified_gmt":"2025-09-19T18:49:02","slug":"cigarettes-after-sex-nadchodzi-z-wyczekiwanym-albumem-xs","status":"publish","type":"post","link":"https:\/\/www.ebilet.pl\/now\/cigarettes-after-sex-nadchodzi-z-wyczekiwanym-albumem-xs\/","title":{"rendered":"Cigarettes After Sex nadchodzi z wyczekiwan\u0105 p\u0142yt\u0105 &#8220;X\u2019s&#8221;"},"content":{"rendered":"\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><h2><b>Nadchodzi nowy album!<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Trzeci kr\u0105\u017cek <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/cigarettes-after-sex\"><strong>Cigarettes After Sex<\/strong><\/a> uka\u017ce si\u0119 ju\u017c 12 lipca nak\u0142adem wytw\u00f3rni Partisan Records. To pierwsze nowe wydawnictwo grupy od wydanej w 2019 roku p\u0142yty <strong>\u201cCry\u201d<\/strong>, dzi\u0119ki kt\u00f3rej CAS stali\u00a0 si\u0119 jednym z najbardziej popularnych zespo\u0142\u00f3w indie i ambient-popowych na \u015bwiecie. Tym bardziej fani z niecierpliwo\u015bci\u0105 oczekiwali ich nowego materia\u0142u. Co ju\u017c wiadomo o tym albumie?\u00a0<\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"tickets-slider  section-margin-32\"\n    data-tickets-slider\n    data-item-list-name=\"Karuzela z buttonami\"\n    data-item-list-id=\"karuzela_z_buttonami\"\n    >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"tickets-slider__main\">\n                    <div class=\"tickets-slider__nav tickets-slider__nav--prev\">\n                        <div class=\"button button--withIcon button--theme-white-blur button--size-fixed-48\" data-tickets-slider-prev>\n                            <span class=\"button__icon icon icon-chevron-left\"><\/span>\n                        <\/div>\n                    <\/div>\n                    <div class=\"tickets-slider__nav tickets-slider__nav--next\">\n                        <div class=\"button button--withIcon button--theme-white-blur button--size-fixed-48\" data-tickets-slider-next>\n                            <span class=\"button__icon icon icon-chevron-right\"><\/span>\n                        <\/div>\n                    <\/div>\n                    <div class=\"tickets-slider__slider swiper\" data-tickets-slider-slider>\n                        <div class=\"tickets-slider__sliderWrapper swiper-wrapper\">\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"103616\"\n                                    data-name=\"Another Pink Floyd\"\n                                    data-brand=\"FANTOM MEDIA Micha\u0142 Kapu\u015bciarz\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Bia\u0142ystok, Gorz\u00f3w Wielkopolski, Krak\u00f3w i inne\"\n                                    data-venue=\"Arena Ostr\u00f3w\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/another-pink-floyd-marek-raduli\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/vv5cv4hb\/another-pink-floyd-pion-736.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/another-pink-floyd-marek-raduli\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"29466\"\n                                    data-name=\"Queen Symfonicznie \u2013 trasa XV-lecia\"\n                                    data-brand=\"Piosenka Plus\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Bia\u0142ystok, Bielsko-Bia\u0142a, Gda\u0144sk i inne\"\n                                    data-venue=\"Filharmonia Zielonog\u00f3rska im. Tadeusza Bairda\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/queen-symfonicznie\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/by0fduy3\/queensymfoniczniexvlecie-1.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/queen-symfonicznie\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"68779\"\n                                    data-name=\"Zadzwo\u0144cie po milicj\u0119\"\n                                    data-brand=\"VISUAL PRODUCTION Sp. z o.o. \"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Gorz\u00f3w Wielkopolski, Katowice, \u0141\u00f3d\u017a i inne\"\n                                    data-venue=\"Hala Spodek\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/zadzwoncie-po-milicje\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/z5pgmlm0\/ebilet-552x736px-7b19a255-52f8-414a-ba5c-940dd8da8a6c.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/zadzwoncie-po-milicje\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"94046\"\n                                    data-name=\"BLIND CHANNEL\"\n                                    data-brand=\"Winiary Bookings sp. z o. o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Krak\u00f3w, Warszawa\"\n                                    data-venue=\"Klub Proxima\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/blind-channel\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/heakcnq4\/blind-channel-ebilet-strona-wydarzenia-pion-wspo-lne.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/blind-channel\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"94910\"\n                                    data-name=\"Muzyka Zespo\u0142u Nirvana Symfonicznie\"\n                                    data-brand=\"Piosenka Plus\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Gorz\u00f3w Wielkopolski, \u0141a\u0144cut, Nysa i inne\"\n                                    data-venue=\"Miejskie Centrum Kultury, Gorz\u00f3w Wielkopolski\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/nirvana-symfonicznie\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/paofi20m\/552x763-63f08d4d-3f99-0184-5010-e673682fe97f.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/nirvana-symfonicznie\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"10619\"\n                                    data-name=\"\u015awietliki\"\n                                    data-brand=\"Fundacja Student\u00f3w i Absolwent\u00f3w AGH w Krakowie\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Krak\u00f3w\"\n                                    data-venue=\"Klub Studio\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/swietliki\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/bb1bacv5\/st-swietliki-05-12_ebilet-552x736-1.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/swietliki\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"6263\"\n                                    data-name=\"IRA\"\n                                    data-brand=\"Agencja Artystyczna Brussa Jaros\u0142aw Brussa Iwona Brussa Zuzanna \"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Toru\u0144, Tychy, Wroc\u0142aw\"\n                                    data-venue=\"Teatr Ma\u0142y  w Tychach\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/ira\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/s35cup1a\/552x736-2-1-bcc906fe-3e20-4a00-8fad-3bc2b5052fe4.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/ira\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"121218\"\n                                    data-name=\"Diary Of Dreams\"\n                                    data-brand=\"Progresja\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Warszawa\"\n                                    data-venue=\"Progresja\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/diary-of-dreams\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/xs2l1roa\/pion-dod-1c2e216b-9c55-4209-af9d-317afb962913.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/diary-of-dreams\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"5751\"\n                                    data-name=\"Freddie Mercury Rock-Operowo przy \u015bwiecach\"\n                                    data-brand=\"Copernicus Sp\u00f3\u0142ka z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Bielsko-Bia\u0142a, Bydgoszcz, Krak\u00f3w i inne\"\n                                    data-venue=\"Sala Redutowa - Kamienica &quot;Pod Or\u0142em&quot;\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/freddie-mercury-rock-operowo\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/xrhpj4s5\/freddie-mercury-opera-show-552x736-px-e2f617db-f1c6-4e8d-a457-635fc1b031af.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/freddie-mercury-rock-operowo\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"151582\"\n                                    data-name=\"Zvezda po imeni Solnce - KINO Symphony Tribute\"\n                                    data-brand=\"Luckystar,s.r.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Gda\u0144sk, Warszawa\"\n                                    data-venue=\"Teatr Palladium w Warszawie\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/kino\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ff1my13k\/tsoy-552_736-300de170-4d6e-4339-888e-b2369357bd21.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/kino\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"148914\"\n                                    data-name=\"Baby Lasagna\"\n                                    data-brand=\"Winiary Bookings sp. z o. o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Krak\u00f3w, Pozna\u0144, Warszawa\"\n                                    data-venue=\"Klub Tama\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/baby-lasagna\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/s0fjvlmt\/baby-lasagna-ebilet-strona-wydarzenia-pion-wsp_lne-bcc5aef0-8eb2-47c6-b22d-5d746c61b5ca.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/baby-lasagna\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"169635\"\n                                    data-name=\"Manchester trasa 20 lat\"\n                                    data-brand=\"Lizard King\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Gda\u0144sk, Rybnik, Toru\u0144 i inne\"\n                                    data-venue=\"Odessa Club\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/manchester\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ek1byiez\/87-9d1709dc-da26-487a-a9a2-aa0e33f2ead4.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/manchester\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"174489\"\n                                    data-name=\"Rock przy \u015bwiecach\"\n                                    data-brand=\"Royal Tributes Sp. z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Bia\u0142ystok, Kielce, Krak\u00f3w i inne\"\n                                    data-venue=\"Nowohuckie Centrum Kultury w Krakowie\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/rock-przy-swiecach\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/jtxjvwxg\/552x736-1bede421-ef80-4b28-8022-46d9748e5b60.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/rock-przy-swiecach\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"178032\"\n                                    data-name=\"Muzyka Queen i Eltona Johna na 28. pi\u0119trze\"\n                                    data-brand=\"SVITLO CONCERT Sp. z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Warszawa\"\n                                    data-venue=\"Sky Hall by Svitlo Concert\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/muzyka-queen-i-eltona-johna\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/xk2fokit\/552_736-queen-i-elton-john-45ba92a6-63e6-4fcc-a7dd-a8d110220060.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/muzyka-queen-i-eltona-johna\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"178059\"\n                                    data-name=\"Klasyka Rocka na 28. pi\u0119trze\"\n                                    data-brand=\"SVITLO CONCERT Sp. z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Warszawa\"\n                                    data-venue=\"Sky Hall by Svitlo Concert\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/klasyka-rocka-na-28-pietrze\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/bomlu01s\/552_736-klasyka-rocka-1-524982de-4c74-453d-9759-d38cea5c4ffe.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/klasyka-rocka-na-28-pietrze\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"181566\"\n                                    data-name=\"Queen Classic Concert By Candle Glow\"\n                                    data-brand=\"Copernicus Sp\u00f3\u0142ka z o.o.\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Krak\u00f3w, Warszawa\"\n                                    data-venue=\"Klasztor O.O. Bernardyn\u00f3w\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/royal-chopin-hall\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/kyndi0f0\/queen-classic-krak_w-552x736-px-by-candle-glow-7c7a331d-b9d9-432e-b4ab-2b0a679f4a61.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/royal-chopin-hall\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"182461\"\n                                    data-name=\"&quot;M\u00f3wi\u0105 o mnie w mie\u015bcie...&quot; - Urodziny Ry\u015bka Riedla\"\n                                    data-brand=\"SWIK Nasze Miasto Wroc\u0142aw\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Wroc\u0142aw\"\n                                    data-venue=\"Stary Klasztor\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/urodziny-ryska-riedla\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/j0klrcnc\/600x850-16-1-dbc22d07-f6af-4895-bec5-188342de3666.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/urodziny-ryska-riedla\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"64455\"\n                                    data-name=\"Budka Suflera\"\n                                    data-brand=\"AGENCJA ARTYSTYCZNA BRUSSA ZUZANNA BRUSSA\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"\u0141\u00f3d\u017a, Pozna\u0144, Szczecin\"\n                                    data-venue=\"Aula Uniwersytetu im. Adama Mickiewicza\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/budka-suflera\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/nodjpqhc\/552x736-440b2d4b-96e6-4745-b1df-734d2a4584e2.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/budka-suflera\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"66419\"\n                                    data-name=\"Clan of Xymox\"\n                                    data-brand=\"SWIK Nasze Miasto Wroc\u0142aw\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Wroc\u0142aw\"\n                                    data-venue=\"Stary Klasztor\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/clan-of-xymox\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/mh5bsm2p\/clan-of-xymox-600-x-850-px-1-76107dc8-3d1a-40a9-abb7-ccac953c5388.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/clan-of-xymox\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                            <div class=\"tickets-slider__sliderItem swiper-slide\"\n                                    data-id=\"183034\"\n                                    data-name=\"Koncert przy \u015bwiecach \u2013 Rockowe ballady\"\n                                    data-brand=\"Fundacja na Rzecz Pomocy Pestka\"\n                                    data-category=\"muzyka\"\n                                    data-subcategory=\"rock\"\n                                    data-city=\"Wroc\u0142aw\"\n                                    data-venue=\"Aula NOT\">\n                                    <div class=\"tickets-slider__sliderCard\">\n                                        \n<div class=\"card-ticket\">\n        <div class=\"card-ticket__image\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/rockowe-ballady\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ct4htuvt\/2_rockowe-ballady-552-x-736-px-fd77277d-4666-40e0-ac40-98e075eed508.webp\" alt=\"Plakat wydarzenia\" \/>\n        <\/a>\n    <\/div>\n             \n    <div class=\"card-ticket__link\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/rockowe-ballady\" class=\"button button--theme-primary-yellow button--withIconLeft button--size-small\">\n            <span class=\"button__icon icon icon-ticket\"><\/span>\n            <p class=\"button__text typo-16 f-600\">Kup bilet<\/p>\n        <\/a>\n    <\/div>\n    <\/div>                                    <\/div>\n                                <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><h2><strong>X\u2019s<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Nostalgiczna i intensywnie obrazowa muzyka CAS zar\u00f3wno na wspomnianym albumie \u201cCry\u201d, jak i <\/span><span style=\"font-weight: 400;\">na debiutanckim, imienny kr\u0105\u017cku wydanym w 2017 roku czerpa\u0142a inspiracj\u0119 z <\/span><span style=\"font-weight: 400;\">amalgamatu zwi\u0105zk\u00f3w uczuciowych lidera grupy, <strong>Grega Gonzaleza<\/strong>. Nie inaczej b\u0119dzie i tym razem. Zgodnie z zapowiedzi\u0105 prasow\u0105 <strong>\u201cX\u2019s&#8221;<\/strong> koncentruje si\u0119 na trwaj\u0105cej blisko cztery lata mi\u0142osnej relacji frontmana CAS. Autorefleksja zwi\u0105zana z rozpadem zwi\u0105zku sta\u0142a si\u0119 impulsem w procesie tw\u00f3rczym, a ten podzia\u0142 na niego, jak katharsis:\u00a0<\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"quote-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"quote-block__wrapper\">\n                    <p class=\"quote-block__quote typo-32\">&#8220;Ta p\u0142yta brzmi naprawd\u0119 brutalnie&#8221; &#8211; przyznaje Gonzalez. &#8220;To by\u0142o tak intensywne do\u015bwiadczenie i naprawd\u0119 pi\u0119kne, dop\u00f3ki trwa\u0142o. Chodzi o romans, ale tak\u017ce o to, kim by\u0142em w tamtym momencie. M\u00f3g\u0142bym usi\u0105\u015b\u0107 i porozmawia\u0107 z kim\u015b o tej stracie, ale to by nie wystarczy\u0142o. Musia\u0142em o tym napisa\u0107, za\u015bpiewa\u0107, mie\u0107 muzyk\u0119. Dopiero potem mog\u0142em zacz\u0105\u0107 wszystko analizowa\u0107 i wyci\u0105ga\u0107 wnioski. Albo po prostu prze\u017cy\u0107 to na nowo &#8211; w dobry spos\u00f3b\u201d.<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><h2><strong>Tejano Blue<\/strong><\/h2>\n<p>Pierwszy singiel promuj\u0105cy p\u0142yt\u0119 pojawi\u0142 si\u0119 w lutym 2024 roku. <strong>&#8220;Tejano Blue&#8221;<\/strong>, to &#8211; jak t\u0142umaczy\u0142 Gonzalez &#8211; uk\u0142on w stron\u0119 jego teksa\u0144skiego dzieci\u0144stwa i tamtejszej muzyki:<\/p>\n<p>\u201cDorasta\u0142em w El Paso i muzyka Tejano jest tam bardzo popularna. Mo\u017cna by\u0142o p\u00f3j\u015b\u0107 do wielu bar\u00f3w w mie\u015bcie i us\u0142ysze\u0107 artyst\u00f3w takich jak Selena, Los \u00c1ngeles Azules i La Mafia. Ta muzyka by\u0142a wok\u00f3\u0142 mnie w tamtych czasach, ale zawsze j\u0105 odrzuca\u0142em i ci\u0105gn\u0119\u0142o mnie do wszystkiego innego, co mnie poci\u0105ga\u0142o. Wiele lat p\u00f3\u017aniej, kiedy mieszka\u0142em ju\u017c w Nowym Jorku, w ko\u0144cu zacz\u0105\u0142em s\u0142ucha\u0107 Como La Flor Seleny. W tym samym czasie s\u0142ucha\u0142em te\u017c du\u017co Cocteau Twins. Wpad\u0142em wtedy na pomys\u0142, aby spr\u00f3bowa\u0107 jako\u015b po\u0142\u0105czy\u0107 te d\u017awi\u0119ki, co wydawa\u0142o si\u0119 mo\u017ce nieco dziwne\u201d &#8211; m\u00f3wi Greg.<\/p>\n<p>Ten eksperyment si\u0119 op\u0142aci\u0107. Od czasu wydania &#8220;Tejano Blue&#8221; singiel zdoby\u0142 ponad 27 milion\u00f3w odtworze\u0144, znalaz\u0142 si\u0119 na 43 playlistach Spotify, a sam zesp\u00f3\u0142 przekroczy\u0142 granic\u0119 4 milion\u00f3w obserwuj\u0105cych na Instagramie.<\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Tejano Blue - Cigarettes After Sex\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/--JuMkludKM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<section class=\"gap-block  section-margin-32 section-margin-32\"><\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><h2><b>Dark Vacay<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">W po\u0142owie kwietnia grupa udost\u0119pni\u0142a drugi singiel z nadchodz\u0105cego kr\u0105\u017cka &#8211; spokojn\u0105, melancholijn\u0105 ballad\u0119 <strong>&#8220;Dark Vacay&#8221;<\/strong>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cTa piosenka jest o romansie, kt\u00f3ry mia\u0142em kilka lat temu. Pojechali\u015bmy razem w tras\u0119 i mieli\u015bmy szcz\u0119\u015bcie odwiedzi\u0107 te wszystkie wspania\u0142e miejsca, na pocz\u0105tku dobrze si\u0119 bawi\u0105c. Jednak w miar\u0119 trwania trasy wszystko zacz\u0119\u0142o si\u0119 rozpada\u0107 i ostatecznie zerwali\u015bmy ze sob\u0105. \u017ba\u0142owa\u0142em, \u017ce w jaki\u015b spos\u00f3b nie uda\u0142o nam si\u0119 dostrzec ca\u0142ego otaczaj\u0105cego nas pi\u0119kna, zanim by\u0142o za p\u00f3\u017ano. \u017ba\u0142uj\u0119, \u017ce nie potrafi\u0142em wydosta\u0107 si\u0119 z tego klaustrofobicznego nastawienia i by\u0107 wdzi\u0119cznym za wszystko, co si\u0119 wydarzy\u0142o. To po prostu koniec pewnego romansu i pr\u00f3ba dostrze\u017cenia w tym pi\u0119kna\u201d &#8211; opowiada o kontek\u015bcie zwi\u0105zanym z powstaniem &#8220;Dark Vacay&#8221; Gonzalez.<\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Dark Vacay - Cigarettes After Sex\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/-gDUUp5iKns?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<section class=\"gap-block  section-margin-32 section-margin-32\"><\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><h2><b>Baby Blue Movie<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Zupe\u0142nie inny charakter ma <strong>&#8220;Baby Blue Movie&#8221;<\/strong> &#8211; trzeci singiel promuj\u0105cy &#8220;X&#8217;s&#8221;, kt\u00f3ry muzycy wypu\u015bcili 4 czerwca. Eteryczna, popowa piosenka tytularnie odwo\u0142uje si\u0119 do \u2026 film\u00f3w dla doros\u0142ych. Romantyczny, pe\u0142en czu\u0142o\u015bci pejza\u017cem d\u017awi\u0119kowym celowo kontrastuje tutaj z tekstem opowiadaj\u0105cym o pragnieniach, kt\u00f3rym do romantyzmu daleko. Jak m\u00f3wi lider CAS, pozwala to dokona\u0107 s\u0142uchaczowi wyboru, w jaki spos\u00f3b chce interpretowa\u0107 ten kawa\u0142ek i na jakiej warstwie &#8211; muzycznej, czy tekstowej &#8211; si\u0119 skupi\u0107:<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201c<\/span><i><span style=\"font-weight: 400;\">Blue movie<\/span><\/i><span style=\"font-weight: 400;\"> to termin okre\u015blaj\u0105cy film porno, wi\u0119c <\/span><i><span style=\"font-weight: 400;\">Baby Blue Movie<\/span><\/i><span style=\"font-weight: 400;\"> jest odniesieniem do softcore porno. Us\u0142ysza\u0142em ten tytu\u0142 wiele lat temu i zrobi\u0142 na mnie ogromne wra\u017cenie. Utw\u00f3r celowo jest bardziej tajemniczy ni\u017c teksty, kt\u00f3re zwykle pisz\u0119. Podoba mi si\u0119 pomys\u0142 pozostawienia s\u0142uchaczowi decyzji, o czym mo\u017ce by\u0107 ta piosenka&#8230;&#8221; &#8211; m\u00f3wi Gonzalez..<\/span><\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Baby Blue Movie - Cigarettes After Sex\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/BeAzmDCWUzI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<section class=\"gap-block  section-margin-32 section-margin-32\"><\/section>\n\n\n<section class=\"text-block  section-margin-32\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"text-block__content\"><h2>Koncerty Cigarettes After Sex w Polsce<\/h2>\n<p>Wydaniu p\u0142yty towarzyszy\u0107 b\u0119dzie ogromna \u015bwiatowa trasa koncertowa. Muzycy ruszaj\u0105 w ni\u0105 z ko\u0144cem sierpnia. W\u015br\u00f3d og\u0142oszonych wyst\u0119p\u00f3w znalaz\u0142y si\u0119 te\u017c dwa koncerty dla polskiej publiczno\u015bci, kt\u00f3re Cigarettes After Sex zagraj\u0105 w Warszawie 5 i 6 listopada w Hali COS Torwar.<\/p>\n<p>Nie mamy jednak dobrych wie\u015bci &#8211; oba koncerty cieszy\u0142y si\u0119 tak du\u017cym zainteresowaniem, \u017ce nied\u0142ugo po tym, jak organizator upubliczni\u0142 informacj\u0119, \u017ce zesp\u00f3\u0142 zagra w Polsce, w zaledwie kilkadziesi\u0105t godzin od tego og\u0142oszenia bilety na oba sto\u0142eczne wyst\u0119py zosta\u0142y wyprzedane.<\/p>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"events-slider-block  section-margin-32\" data-events-slider-block data-carousel-title=\"Gor\u0105ce wydarzenia\" data-carousel-type=\"karuzela_z_t\u0142em\" data-item-list-name=\"Karuzela z t\u0142em Gor\u0105ce wydarzenia\" data-item-list-id=\"karuzela_z_t\u0142em Gor\u0105ce wydarzenia\" >\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-24\">\n                <div class=\"events-slider-block__wrapper\">\n                                            <div class=\"events-slider-block__bg\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554.jpg 1920w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-1024x576.jpg 1024w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-1536x864.jpg 1536w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-1280x720.jpg 1280w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-500x281.jpg 500w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-632x356.jpg 632w, https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/02\/shutterstock_134643554-308x174.jpg 308w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div>\n                                                                <div class=\"events-slider-block__top\">\n                                                            <div class=\"events-slider-block__title desktop\">\n                                    <h2 class=\"typo-h2\">Gor\u0105ce wydarzenia<\/h2>\n                                <\/div>\n                                                                                        <div class=\"events-slider-block__title mobile\">\n                                    <h2 class=\"typo-h2\">Gor\u0105ce wydarzenia<\/h2>\n                                <\/div>\n                                                    <\/div>\n                                                            <div class=\"events-slider-block__main\">\n                        <div class=\"events-slider-block__nav events-slider-block__nav--prev\">\n                            <div class=\"button button--withIcon button--theme-white-blur button--size-fixed-48\" data-events-prev>\n                                <span class=\"button__icon icon icon-chevron-left\"><\/span>\n                            <\/div>\n                        <\/div>\n                        <div class=\"events-slider-block__nav events-slider-block__nav--next\">\n                            <div class=\"button button--withIcon button--theme-white-blur button--size-fixed-48\" data-events-next>\n                                <span class=\"button__icon icon icon-chevron-right\"><\/span>\n                            <\/div>\n                        <\/div>\n                        <div class=\"events-slider-block__slider\">\n                            <div class=\"swiper\" data-events-slider>\n                                <div class=\"events-slider-block__sliderWrapper swiper-wrapper\">\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/opener-festival\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/qkso1del\/opene_2027_tameimpala_552x736_ebilet-1d7aa61e-0a2a-4f3b-b538-d84518354aa2.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Open&#8217;er Festival 2027<\/p>\n            <\/div>\n            <div class=\"card-event__date\">30.06.2027-30.06.2027<\/div>\n            <div class=\"card-event__location\">Gdynia<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/sport\/sporty-druzynowe\/koszykowka-mecz\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/hoxono4g\/podstawowe_portal-98225706-f40f-4253-9b63-9f6c375fb13f.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Kwalifikacje do Mistrzostw \u015awiata w koszyk\u00f3wce m\u0119\u017cczyzn 2027: Polska \u2013 Chorwacja<\/p>\n            <\/div>\n            <div class=\"card-event__date\">27.11.2026-27.11.2026<\/div>\n            <div class=\"card-event__location\">Gliwice<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/pitbull\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/5lzfwzwf\/pitbull_552x736-51986cca-48f5-4419-a9c5-cba531ed65a3.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Pitbull &#8211; I&#8217;m Back!<\/p>\n            <\/div>\n            <div class=\"card-event__date\">27.11.2026-27.11.2026<\/div>\n            <div class=\"card-event__location\">Gda\u0144sk\/Sopot, \u0141\u00f3d\u017a<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/take-that\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/eiqdozli\/ebilet-552x736-take-that.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Take That<\/p>\n            <\/div>\n            <div class=\"card-event__date\">13.06.2027-13.06.2027<\/div>\n            <div class=\"card-event__location\">Warszawa<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/biznes\/wystawa\/van-gogh\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/rx0pgtm4\/nowa-ebilet-_vg-__-lublin_-552-736-5ddf74a4-5cec-41cd-9f00-a4baa0f7a221.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>VAN GOGH \u2013 Wystawa Immersyjna &#8211; Lublin<\/p>\n            <\/div>\n            <div class=\"card-event__date\">15.09.2026-15.09.2026<\/div>\n            <div class=\"card-event__location\">Lublin<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/hip-hop-rap\/gombao33\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ctcikvkb\/gombao_bez_napisu-2ebe28b7-760a-4987-8d6c-0cb2fe6f2203.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>G33 Tour &#8211; Tadeo x Szczepan x Wygu\u015b x Mata<\/p>\n            <\/div>\n            <div class=\"card-event__date\">12.09.2026-12.09.2026<\/div>\n            <div class=\"card-event__location\">Bydgoszcz, Gwi\u017adziny, Kra\u015bnik i inne<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/hip-hop-rap\/otsochodzi\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ucuizr2w\/tt-552-x-736-kopia.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Otsochodzi &#8211; RIOTT<\/p>\n            <\/div>\n            <div class=\"card-event__date\">01.10.2026-01.10.2026<\/div>\n            <div class=\"card-event__location\">Gda\u0144sk, Krak\u00f3w, Pozna\u0144 i inne<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/russell-crowe\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/dajolyng\/rusel_pion-738c048c-2504-4de3-a226-d83518cf8463.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Russell Crowe\u2019s Indoor Garden Party<\/p>\n            <\/div>\n            <div class=\"card-event__date\">05.06.2027-05.06.2027<\/div>\n            <div class=\"card-event__location\">\u0106miel\u00f3w<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/piosenka\/koncert-koled-i-pastoralek-golec-uorkiestra\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/sqlacf5s\/golec_552x736_ebilet-c90c1dab-7443-46cc-b6f7-252554a5cab4.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Golec uOrkiestra &#8211; Koncert Kol\u0119d i Pastora\u0142ek<\/p>\n            <\/div>\n            <div class=\"card-event__date\">18.12.2026-18.12.2026<\/div>\n            <div class=\"card-event__location\">Bielsko-Bia\u0142a, Bydgoszcz, Gda\u0144sk i inne<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/tokio-hotel\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/i02j3uly\/tokio-hotel-552.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Tokio Hotel<\/p>\n            <\/div>\n            <div class=\"card-event__date\">19.08.2027-19.08.2027<\/div>\n            <div class=\"card-event__location\">Warszawa<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/up-to-date-festival\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/jfdlnoqn\/ebilet-552x736-portal-wersja-2-c38ddeaf-bf05-4f54-9e4d-377e6b572335.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Up To Date Festival 2027<\/p>\n            <\/div>\n            <div class=\"card-event__date\">27.05.2027-27.05.2027<\/div>\n            <div class=\"card-event__location\">Bia\u0142ystok<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/olsztyn-green-festival\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ivzhtv3z\/1080x1350_ogf_edycja_2027-18faf89b-3a6e-4aa9-b07b-593f24448a27.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Olsztyn Green Festival 2027<\/p>\n            <\/div>\n            <div class=\"card-event__date\">13.08.2027-13.08.2027<\/div>\n            <div class=\"card-event__location\">Olsztyn<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/sport\/sporty-walki\/ksw-gala\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/cz4hwoy5\/ksw122_552x736-kopia-2bfd4e82-ebbc-475a-901b-7cd82d226339.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>XTB KSW 122<\/p>\n            <\/div>\n            <div class=\"card-event__date\">10.10.2026-10.10.2026<\/div>\n            <div class=\"card-event__location\">Rzesz\u00f3w<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                    <div class=\"events-slider-block__sliderItem swiper-slide\">\n                                    \n<div class=\"card-event  card-event--size-small\">\n        <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/fontaines-dc\" target=\"_blank\" class=\"card-event__link\" rel=\"nofollow noopener\"><\/a>\n        <div class=\"card-event__wrapper\">\n        <div class=\"card-event__image\">\n            <img decoding=\"async\" src=\"https:\/\/www.ebilet.pl\/media\/cms\/media\/ovge4bna\/fontaines_dc_portal_552x736.webp\" alt=\"\">\n        <\/div>\n        <div class=\"card-event__data\">\n            <div class=\"card-event__name\">\n                <p>Fontaines D.C. EU TOUR 2026<\/p>\n            <\/div>\n            <div class=\"card-event__date\">31.10.2026-31.10.2026<\/div>\n            <div class=\"card-event__location\">\u0141\u00f3d\u017a<\/div>\n        <\/div>\n    <\/div>\n<\/div>                                    <\/div>\n                                                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"events-slider-block__events swiper\" data-events-events-descriptions>\n                            <div class=\"events-slider-block__eventsWrapper swiper-wrapper\">\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/opener-festival\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Open&#039;er Festival 2027<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        30.06.2027-03.07.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Gdynia<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/sport\/sporty-druzynowe\/koszykowka-mecz\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Kwalifikacje do Mistrzostw \u015awiata w koszyk\u00f3wce m\u0119\u017cczyzn 2027: Polska \u2013 Chorwacja<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        27.11.2026-27.11.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Gliwice<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/pitbull\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Pitbull &#8211; I&#039;m Back!<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        27.11.2026-03.12.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Gda\u0144sk\/Sopot, \u0141\u00f3d\u017a<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/take-that\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Take That<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        13.06.2027-13.06.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Warszawa<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/biznes\/wystawa\/van-gogh\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>VAN GOGH \u2013 Wystawa Immersyjna &#8211; Lublin<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        15.09.2026-31.12.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Lublin<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/hip-hop-rap\/gombao33\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>G33 Tour &#8211; Tadeo x Szczepan x Wygu\u015b x Mata<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        12.09.2026-04.10.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Bydgoszcz, Gwi\u017adziny, Kra\u015bnik i inne<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/hip-hop-rap\/otsochodzi\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Otsochodzi &#8211; RIOTT<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        01.10.2026-03.12.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Gda\u0144sk, Krak\u00f3w, Pozna\u0144 i inne<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/russell-crowe\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Russell Crowe\u2019s Indoor Garden Party<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        05.06.2027-05.06.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">\u0106miel\u00f3w<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/piosenka\/koncert-koled-i-pastoralek-golec-uorkiestra\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Golec uOrkiestra &#8211; Koncert Kol\u0119d i Pastora\u0142ek<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        18.12.2026-17.01.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Bielsko-Bia\u0142a, Bydgoszcz, Gda\u0144sk i inne<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/pop\/tokio-hotel\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Tokio Hotel<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        19.08.2027-19.08.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Warszawa<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/up-to-date-festival\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Up To Date Festival 2027<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        27.05.2027-28.05.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Bia\u0142ystok<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/festiwale\/olsztyn-green-festival\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Olsztyn Green Festival 2027<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        13.08.2027-13.08.2027                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Olsztyn<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/sport\/sporty-walki\/ksw-gala\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>XTB KSW 122<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        10.10.2026-10.10.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">Rzesz\u00f3w<\/div>\n                                <\/div>\n                                                            <div class=\"events-slider-block__eventsItem swiper-slide\">\n                                    <a href=\"https:\/\/www.ebilet.pl\/muzyka\/rock\/fontaines-dc\" target=\"_blank\" class=\"events-slider-block__eventsName\">\n                                        <p>Fontaines D.C. EU TOUR 2026<\/p>\n                                    <\/a>\n                                    <div class=\"events-slider-block__eventsDate\">\n                                        31.10.2026-31.10.2026                                    <\/div>\n                                    <div class=\"events-slider-block__eventsLocation\">\u0141\u00f3d\u017a<\/div>\n                                <\/div>\n                                                        <\/div>\n                        <\/div>\n                        <div class=\"events-slider-block__pagination\">\n                            <div class=\"swiper-pagination slider-pagination slider-pagination--theme-white\" data-events-slider-pagination><\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"events-slider-block__bottom\">\n                                                                                <div class=\"events-slider-block__link desktop\">\n                                    <a\n                                        class=\"button button--size-small button--theme-primary-yellow button--withIconLeft\"\n                                        href=\"https:\/\/www.ebilet.pl\/\">\n                                                                                    <div class=\"button__icon\"><img loading=\"lazy\" decoding=\"async\" width=\"30\" height=\"30\" src=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/01\/ticket-cinema-entertainment-coupon-discount-sale_30px.png\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\n                                                                                <p class=\"button__text typo-18\">Kup na eBilet.pl<\/p>\n                                    <\/a>\n                                <\/div>\n                                                                                <div class=\"events-slider-block__link mobile\">\n                                    <a\n                                        class=\"button button--size-small button--theme-primary-yellow button--withIconLeft\"\n                                        href=\"https:\/\/www.ebilet.pl\/\">\n                                                                                    <div class=\"button__icon\"><img loading=\"lazy\" decoding=\"async\" width=\"30\" height=\"30\" src=\"https:\/\/www.ebilet.pl\/now\/app\/uploads\/2024\/01\/ticket-cinema-entertainment-coupon-discount-sale_30px.png\" class=\"attachment-full size-full\" alt=\"\" \/><\/div>\n                                                                                <p class=\"button__text typo-18\">Kup na eBilet.pl<\/p>\n                                    <\/a>\n                                <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Trwa wielkie odliczanie do premiery d\u0142ugo wyczekiwanego trzeciego studyjnego albumu Cigarettes After Sex. Grupa wypu\u015bci kr\u0105\u017cek &#8220;X&#8217;s&#8221; ju\u017c 12 lipca. Co wiemy o tym wydawnictwie? Pos\u0142uchaj singli i dowiedz si\u0119, co z koncertami w Polsce.<\/p>\n","protected":false},"author":8,"featured_media":27293,"comment_status":"open","ping_status":"open","sticky":false,"template":"page-templates\/article-default.php","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"article_tag":[342,65,67,26,31,82,41,43],"article_type":[554],"class_list":["post-26619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","article_tag-abient","article_tag-indie","article_tag-indie-rock","article_tag-koncerty","article_tag-muzyka","article_tag-plyty","article_tag-pop","article_tag-rock","article_type-muzyka"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/posts\/26619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/comments?post=26619"}],"version-history":[{"count":3,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/posts\/26619\/revisions"}],"predecessor-version":[{"id":27420,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/posts\/26619\/revisions\/27420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/media\/27293"}],"wp:attachment":[{"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/media?parent=26619"}],"wp:term":[{"taxonomy":"article_tag","embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/article_tag?post=26619"},{"taxonomy":"article_type","embeddable":true,"href":"https:\/\/www.ebilet.pl\/now\/wp-json\/wp\/v2\/article_type?post=26619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}